{"id":20103,"date":"2025-01-31T10:40:17","date_gmt":"2025-01-31T08:40:17","guid":{"rendered":"https:\/\/ornelladesign.ro\/product\/desk-calendar-with-plexiglass-stand\/"},"modified":"2026-03-22T15:32:11","modified_gmt":"2026-03-22T13:32:11","slug":"desk-calendar-with-plexiglass-stand","status":"publish","type":"product","link":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/","title":{"rendered":"Desk Calendar with Plexiglass Stand"},"content":{"rendered":"<p>A6 Calendar: 6 sheets \/ 12 + 1 pages<\/p>\n<p>Desk calendar<\/p>\n<p>White Plexiglass Stand<\/p>\n<p>For other dimensions or larger quantities, please submit a quote request.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prices are expressed in Lei and do not include VAT<\/p>\n","protected":false},"featured_media":20105,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[233],"product_tag":[],"class_list":["post-20103","product","type-product","status-publish","has-post-thumbnail","product_cat-digital-printing-offset-printing","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desk Calendar with Plexiglass Stand - Print Timisoara - Ornella Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desk Calendar with Plexiglass Stand - Print Timisoara - Ornella Design\" \/>\n<meta property=\"og:description\" content=\"Prices are expressed in Lei and do not include VAT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/\" \/>\n<meta property=\"og:site_name\" content=\"Print Timisoara - Ornella Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OrnellaDesignTimisoara\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-22T13:32:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2025\/01\/osd_calendar-plexi-2-e1738313752965.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"858\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/\",\"url\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/\",\"name\":\"Desk Calendar with Plexiglass Stand - Print Timisoara - Ornella Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ornelladesign.ro\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/osd_calendar-plexi-2-e1738313752965.jpg\",\"datePublished\":\"2025-01-31T08:40:17+00:00\",\"dateModified\":\"2026-03-22T13:32:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ornelladesign.ro\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/osd_calendar-plexi-2-e1738313752965.jpg\",\"contentUrl\":\"https:\\\/\\\/ornelladesign.ro\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/osd_calendar-plexi-2-e1738313752965.jpg\",\"width\":858,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/produs\\\/desk-calendar-with-plexiglass-stand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desk Calendar with Plexiglass Stand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/\",\"name\":\"Print Timisoara - Ornella Design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/#organization\",\"name\":\"Print Timisoara - Ornella Design\",\"url\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ornelladesign.ro\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-OSD_LOGO_new_2022_vector-1-only-logo.webp\",\"contentUrl\":\"https:\\\/\\\/ornelladesign.ro\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-OSD_LOGO_new_2022_vector-1-only-logo.webp\",\"width\":512,\"height\":512,\"caption\":\"Print Timisoara - Ornella Design\"},\"image\":{\"@id\":\"https:\\\/\\\/ornelladesign.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OrnellaDesignTimisoara\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ornella-design\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desk Calendar with Plexiglass Stand - Print Timisoara - Ornella Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/","og_locale":"en_US","og_type":"article","og_title":"Desk Calendar with Plexiglass Stand - Print Timisoara - Ornella Design","og_description":"Prices are expressed in Lei and do not include VAT","og_url":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/","og_site_name":"Print Timisoara - Ornella Design","article_publisher":"https:\/\/www.facebook.com\/OrnellaDesignTimisoara","article_modified_time":"2026-03-22T13:32:11+00:00","og_image":[{"width":858,"height":708,"url":"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2025\/01\/osd_calendar-plexi-2-e1738313752965.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/","url":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/","name":"Desk Calendar with Plexiglass Stand - Print Timisoara - Ornella Design","isPartOf":{"@id":"https:\/\/ornelladesign.ro\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/#primaryimage"},"image":{"@id":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/#primaryimage"},"thumbnailUrl":"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2025\/01\/osd_calendar-plexi-2-e1738313752965.jpg","datePublished":"2025-01-31T08:40:17+00:00","dateModified":"2026-03-22T13:32:11+00:00","breadcrumb":{"@id":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/#primaryimage","url":"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2025\/01\/osd_calendar-plexi-2-e1738313752965.jpg","contentUrl":"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2025\/01\/osd_calendar-plexi-2-e1738313752965.jpg","width":858,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/ornelladesign.ro\/en\/produs\/desk-calendar-with-plexiglass-stand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/ornelladesign.ro\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/ornelladesign.ro\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Desk Calendar with Plexiglass Stand"}]},{"@type":"WebSite","@id":"https:\/\/ornelladesign.ro\/en\/#website","url":"https:\/\/ornelladesign.ro\/en\/","name":"Print Timisoara - Ornella Design","description":"","publisher":{"@id":"https:\/\/ornelladesign.ro\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ornelladesign.ro\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ornelladesign.ro\/en\/#organization","name":"Print Timisoara - Ornella Design","url":"https:\/\/ornelladesign.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ornelladesign.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2024\/01\/cropped-OSD_LOGO_new_2022_vector-1-only-logo.webp","contentUrl":"https:\/\/ornelladesign.ro\/wp-content\/uploads\/2024\/01\/cropped-OSD_LOGO_new_2022_vector-1-only-logo.webp","width":512,"height":512,"caption":"Print Timisoara - Ornella Design"},"image":{"@id":"https:\/\/ornelladesign.ro\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OrnellaDesignTimisoara","https:\/\/www.linkedin.com\/company\/ornella-design\/"]}]}},"_links":{"self":[{"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product\/20103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/comments?post=20103"}],"version-history":[{"count":2,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product\/20103\/revisions"}],"predecessor-version":[{"id":20493,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product\/20103\/revisions\/20493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/media\/20105"}],"wp:attachment":[{"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/media?parent=20103"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product_brand?post=20103"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product_cat?post=20103"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ornelladesign.ro\/en\/wp-json\/wp\/v2\/product_tag?post=20103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}